{"id":16630,"date":"2023-06-26T15:51:20","date_gmt":"2023-06-26T15:51:20","guid":{"rendered":"https:\/\/pauquette.com\/servicios-forenses\/"},"modified":"2025-06-03T15:50:18","modified_gmt":"2025-06-03T15:50:18","slug":"servicios-forenses","status":"publish","type":"page","link":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/","title":{"rendered":"Servicios forenses"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1420.64px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h1 class=\"p1\"><b>Servicios forenses en el Centro Pauquette<\/b><\/h1>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_3_5 3_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.2%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.2%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p>Los Servicios Forenses del Centro Pauquette est\u00e1n supervisados por la Dra. Valerie Gonsalves. La Dra. Gonsalves se doctor\u00f3 en Psicolog\u00eda Cl\u00ednica con especializaci\u00f3n en Psicolog\u00eda Forense<br \/>\nen 2010. La Dra. Gonsalves complet\u00f3 su Residencia Postdoctoral en el Hospital Estatal de Fulton.<\/p>\n<p>Trabaj\u00f3 como proveedora de tratamiento en el Centro de Tratamiento Seguro Sand Ridge durante unos cinco a\u00f1os. <span style=\"color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-hover);\">Durante este tiempo, desarroll\u00f3 un programa de tratamiento para personas con importantes factores de interferencia en el tratamiento y supervis\u00f3 <\/span><span style=\"color: var(--awb-text-color); font-family: var(--awb-text-font-family); font-size: var(--awb-font-size); font-style: var(--awb-text-font-style); font-weight: var(--awb-text-font-weight); letter-spacing: var(--awb-letter-spacing); text-align: var(--awb-content-alignment); text-transform: var(--awb-text-transform); background-color: var(--awb-bg-color-hover);\">la implantaci\u00f3n de un programa DBT de fidelidad total.<\/span><\/p>\n<p>A continuaci\u00f3n, la Dra. Gonsalves trabaj\u00f3 como Directora de Psicolog\u00eda de la Divisi\u00f3n de Correccionales Comunitarias. En este puesto, colabor\u00f3 en la aplicaci\u00f3n de pr\u00e1cticas basadas en pruebas para tratar a personas implicadas en procesos judiciales. La Dra. Gonsalves ha sido miembro de la Junta de la secci\u00f3n de ATSA de Wisconsin desde 2012. En 2019, la Dra. Gonsalves fue distinguida como miembro de la ATSA.<\/p>\n<p>A lo largo de su carrera, la Dra. Gonsalves se ha especializado en el trabajo con individuos con caracter\u00edsticas de personalidad alteradas, haciendo hincapi\u00e9 en los que tienen conductas sexuales problem\u00e1ticas.<\/p>\n<p>El Centro Pauquette ofrece evaluaci\u00f3n, tratamiento, formaci\u00f3n y consulta a las personas implicadas en la justicia y a quienes trabajan con esta poblaci\u00f3n.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_5 2_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:40%;--awb-margin-top-large:0px;--awb-spacing-right-large:4.8%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:4.8%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1366\" height=\"1366\" alt=\"mental health professionals, Psychologist, therapist Madison WI, Portage\" title=\"valerie_gonsalves_square\" src=\"https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=1366%2C1366&#038;ssl=1\" class=\"img-responsive wp-image-16439\" srcset=\"https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=66%2C66&amp;ssl=1 66w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=199%2C199&amp;ssl=1 199w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=322%2C322&amp;ssl=1 322w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=522%2C522&amp;ssl=1 522w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2022\/04\/valerie_gonsalves_square.jpg?w=2100&amp;ssl=1 2100w\" sizes=\"(max-width: 1094px) 100vw, (max-width: 909px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-has-icon fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-single sep-dashed\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#595758;border-top-width:1px;\"><\/div><span class=\"icon-wrapper\" style=\"border-color:#595758;background-color:#595758;font-size:16px;width: 1.75em; height: 1.75em;border-width:1px;padding:1px;margin-top:-0.5px\"><i class=\"fa-balance-scale fas\" style=\"font-size: inherit;color:var(--awb-color1);\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-separator-border sep-single sep-dashed\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#595758;border-top-width:1px;\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\"><h2>Ejemplos de \u00c1reas de Evaluaci\u00f3n y Tratamiento:<\/h2>\n<\/div><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;--awb-circlecolor:var(--awb-custom11);--awb-circle-yes-font-size:14.08px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Evaluaciones de la capacidad procesal<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Estado mental en el momento del delito Evaluaciones<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Evaluaciones de la capacidad parental<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Comportamientos sexuales problem\u00e1ticos (adultos y ni\u00f1os)<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Control de la ira (individual o en grupo)<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Consumo de sustancias<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Caracter\u00edsticas de personalidad alteradas que dan lugar a un comportamiento delictivo<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-balance-scale fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Violencia dom\u00e9stica<\/div><\/li><\/ul><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:4%;width:100%;\"><\/div><div class=\"fusion-text fusion-text-4\"><h3>Facturaci\u00f3n:<\/h3>\n<p><span style=\"font-weight: 400;\">Algunos servicios pueden facturarse a los seguros comerciales y otros no. El Centro Pauquette no factura a los seguros comerciales el tratamiento de delincuentes sexuales juveniles ni el de violencia dom\u00e9stica. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los dem\u00e1s servicios se determinan caso por caso. <\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><h2>Formaci\u00f3n y consulta:<\/h2>\n<p>Nuestra experiencia nos dice que la formaci\u00f3n se aplica mejor en combinaci\u00f3n con una consulta continua. Por ello, recomendamos a todos que empiecen por hacer que el personal asista: Visi\u00f3n General de las Mejores Pr\u00e1cticas en Psicolog\u00eda Forense (Modelo de Respuesta a las Necesidades de Riesgo).<\/p>\n<p>Se recomienda encarecidamente que, si es posible, las organizaciones consideren la posibilidad de impartir en persona esta formaci\u00f3n inicial para fomentar la participaci\u00f3n del personal.<\/p>\n<p>Las necesidades de formaci\u00f3n y consulta pueden individualizarse seg\u00fan la persona o el organismo.<\/p>\n<h4>Estos pueden incluir:<\/h4>\n<\/div><ul style=\"--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;--awb-circlecolor:var(--awb-custom11);--awb-circle-yes-font-size:14.08px;\" class=\"fusion-checklist fusion-checklist-2 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-chalkboard-teacher fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Visi\u00f3n general del tratamiento de delincuentes sexuales y consulta permanente sobre su aplicaci\u00f3n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-chalkboard-teacher fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Visi\u00f3n general del tratamiento de delincuentes sexuales con j\u00f3venes y consulta y aplicaci\u00f3n continuas<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-chalkboard-teacher fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Visi\u00f3n general del tratamiento para personas condenadas por delitos relacionados con material de explotaci\u00f3n sexual infantil (pornograf\u00eda infantil) y en curso<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-chalkboard-teacher fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Consulta y aplicaci\u00f3n<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon fa-chalkboard-teacher fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Consulta sobre intereses sexuales desviados no delictivos<\/div><\/li><\/ul><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"656\" height=\"464\" alt=\"psychotherapy\" title=\"psychotherapy3 656\" src=\"https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=656%2C464&#038;ssl=1\" class=\"img-responsive wp-image-16331\" srcset=\"https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=199%2C141&amp;ssl=1 199w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=200%2C141&amp;ssl=1 200w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=322%2C228&amp;ssl=1 322w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=400%2C283&amp;ssl=1 400w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=522%2C369&amp;ssl=1 522w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?resize=600%2C424&amp;ssl=1 600w, https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2018\/04\/psychotherapy3-656.jpg?w=656&amp;ssl=1 656w\" sizes=\"(max-width: 1094px) 100vw, (max-width: 909px) 100vw, 600px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:8%;width:100%;\"><\/div><div class=\"fusion-text fusion-text-6\"><h2>Inscr\u00edbete<\/h2>\n<p>Si est\u00e1s interesado en organizar una formaci\u00f3n o una consulta, rellena el siguiente formulario:<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfmfhD9ATGFdUFaVgs24i-nFUkF3J-fPKbwUvwNaJ-PfDn_LQ\/viewform\"><span class=\"fusion-button-icon-divider button-icon-divider-left\"><i class=\"fa-edit fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-left\">Pulsa aqu\u00ed<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":16654,"menu_order":24,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16630","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicios forenses | Pauquette Center<\/title>\n<meta name=\"description\" content=\"El Centro Pauquette ofrece psicoterapia individual para todas las edades: ni\u00f1os, adolescentes, adultos, ancianos, familias y parejas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios forenses | Pauquette Center\" \/>\n<meta property=\"og:description\" content=\"El Centro Pauquette ofrece psicoterapia individual para todas las edades: ni\u00f1os, adolescentes, adultos, ancianos, familias y parejas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/\" \/>\n<meta property=\"og:site_name\" content=\"Pauquette Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pauquettecenter\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T15:50:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pauquette.com\\\/es\\\/servicios-de-salud-mental\\\/servicios-forenses\\\/\",\"url\":\"https:\\\/\\\/pauquette.com\\\/es\\\/servicios-de-salud-mental\\\/servicios-forenses\\\/\",\"name\":\"Servicios forenses | Pauquette Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pauquette.com\\\/es\\\/#website\"},\"datePublished\":\"2023-06-26T15:51:20+00:00\",\"dateModified\":\"2025-06-03T15:50:18+00:00\",\"description\":\"El Centro Pauquette ofrece psicoterapia individual para todas las edades: ni\u00f1os, adolescentes, adultos, ancianos, familias y parejas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pauquette.com\\\/es\\\/servicios-de-salud-mental\\\/servicios-forenses\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pauquette.com\\\/es\\\/servicios-de-salud-mental\\\/servicios-forenses\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pauquette.com\\\/es\\\/servicios-de-salud-mental\\\/servicios-forenses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pauquette.com\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios de Salud Mental\",\"item\":\"https:\\\/\\\/pauquette.com\\\/es\\\/servicios-de-salud-mental\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servicios forenses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pauquette.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/pauquette.com\\\/es\\\/\",\"name\":\"Pauquette Center\",\"description\":\"Compassionate professionals ready to serve your psychological needs.  Serving Columbia, Richland, Sauk, and adjacent counties.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pauquette.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios forenses | Pauquette Center","description":"El Centro Pauquette ofrece psicoterapia individual para todas las edades: ni\u00f1os, adolescentes, adultos, ancianos, familias y parejas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/","og_locale":"es_ES","og_type":"article","og_title":"Servicios forenses | Pauquette Center","og_description":"El Centro Pauquette ofrece psicoterapia individual para todas las edades: ni\u00f1os, adolescentes, adultos, ancianos, familias y parejas.","og_url":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/","og_site_name":"Pauquette Center","article_publisher":"https:\/\/www.facebook.com\/pauquettecenter","article_modified_time":"2025-06-03T15:50:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/","url":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/","name":"Servicios forenses | Pauquette Center","isPartOf":{"@id":"https:\/\/pauquette.com\/es\/#website"},"datePublished":"2023-06-26T15:51:20+00:00","dateModified":"2025-06-03T15:50:18+00:00","description":"El Centro Pauquette ofrece psicoterapia individual para todas las edades: ni\u00f1os, adolescentes, adultos, ancianos, familias y parejas.","breadcrumb":{"@id":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/servicios-forenses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pauquette.com\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Servicios de Salud Mental","item":"https:\/\/pauquette.com\/es\/servicios-de-salud-mental\/"},{"@type":"ListItem","position":3,"name":"Servicios forenses"}]},{"@type":"WebSite","@id":"https:\/\/pauquette.com\/es\/#website","url":"https:\/\/pauquette.com\/es\/","name":"Pauquette Center","description":"Compassionate professionals ready to serve your psychological needs.  Serving Columbia, Richland, Sauk, and adjacent counties.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pauquette.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PakdW4-4ke","jetpack-related-posts":[{"id":16645,"url":"https:\/\/pauquette.com\/es\/formulario-de-contacto-para-nuevos-clientes\/","url_meta":{"origin":16630,"position":0},"title":"Formulario de contacto para nuevos clientes","author":"pauquette18","date":"27 de abril de 2019","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":555,"url":"https:\/\/pauquette.com\/contact-us\/","url_meta":{"origin":16630,"position":1},"title":"Contact Us","author":"pauquette18","date":"13 de abril de 2018","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3485,"url":"https:\/\/pauquette.com\/pauquette-center-for-psychological-services-2-2\/","url_meta":{"origin":16630,"position":2},"title":"Home Page","author":"JoEllen Westendorf","date":"5 de junio de 2020","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/pauquette.com\/wp-content\/uploads\/2025\/11\/1000000339-322x242.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":460,"url":"https:\/\/pauquette.com\/offices-and-locations\/","url_meta":{"origin":16630,"position":3},"title":"Pauquette Center Offices and Locations","author":"pauquette18","date":"12 de abril de 2018","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16682,"url":"https:\/\/pauquette.com\/es\/oficinas-y-ubicaciones-del-centro-pauquette\/","url_meta":{"origin":16630,"position":4},"title":"Oficinas y ubicaciones del Centro Pauquette","author":"pauquette18","date":"12 de abril de 2018","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":64,"url":"https:\/\/pauquette.com\/privacy-policy\/","url_meta":{"origin":16630,"position":5},"title":"Privacy Policy","author":"pauquette18","date":"6 de abril de 2018","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/pages\/16630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/comments?post=16630"}],"version-history":[{"count":5,"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/pages\/16630\/revisions"}],"predecessor-version":[{"id":16851,"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/pages\/16630\/revisions\/16851"}],"up":[{"embeddable":true,"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/pages\/16654"}],"wp:attachment":[{"href":"https:\/\/pauquette.com\/es\/wp-json\/wp\/v2\/media?parent=16630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}